{"id":4916,"date":"2024-02-02T12:19:17","date_gmt":"2024-02-02T17:19:17","guid":{"rendered":"https:\/\/germancastrocaycedo.co\/portal\/?p=4916"},"modified":"2024-07-08T12:03:14","modified_gmt":"2024-07-08T17:03:14","slug":"video-cerrejon-reportajes-sobre-la-corrupcion-en-la-guajira","status":"publish","type":"post","link":"https:\/\/germancastrocaycedo.co\/portal\/2024\/02\/02\/video-cerrejon-reportajes-sobre-la-corrupcion-en-la-guajira\/","title":{"rendered":"VIDEO | CERREJ\u00d3N REPORTAJES SOBRE LA CORRUPCI\u00d3N EN LA GUAJIRA"},"content":{"rendered":"\n<p><strong>Septiembre y octubre de 1982<\/strong>.<\/p>\n\n\n\n<p>El 27 de septiembre, en el horario nocturno de la televisi\u00f3n colombiana, &#8216;Enviado Especial&#8217; present\u00f3 uno de sus episodios m\u00e1s emblem\u00e1ticos y reveladores: \u00abCerrej\u00f3n\u00bb. Bajo la direcci\u00f3n de Germ\u00e1n Castro Caycedo, quien por primera vez apareci\u00f3 con corbata azul ante las c\u00e1maras, el programa prometi\u00f3 y entreg\u00f3 una hora llena de revelaciones impactantes sobre el contrato de explotaci\u00f3n de las minas de carb\u00f3n de El Cerrej\u00f3n en La Guajira, entre Exxon, operando bajo Intercor en Colombia, y Carbocol, una empresa estatal.<\/p>\n\n\n\n<p><strong>PARTE 1:<\/strong><\/p>\n\n\n\n<div id=\"cerrejon1\">\n  <iframe loading=\"lazy\" width=\"560\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/ypZWXIz1pDY?si=nKRr_EhOvDogCWHM\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div>\n\n\n\n<p>Con su estilo caracter\u00edstico, Castro Caycedo desenmascar\u00f3, con documentos y testimonios en mano, irregularidades y cuestionamientos profundos sobre las operaciones en El Cerrej\u00f3n. Entre las acusaciones se encontraban la presencia de personal norteamericano trabajando ilegalmente o sin cumplir con los requisitos necesarios, pero percibiendo salarios exorbitantes; la exclusi\u00f3n de mano de obra colombiana; y cuestiones sobre la elecci\u00f3n de equipos y la participaci\u00f3n de flotas para el transporte del carb\u00f3n, resaltando conflictos de inter\u00e9s evidentes con Exxon.<\/p>\n\n\n\n<p><strong>PARTE 2:<\/strong><\/p>\n\n\n\n<div id=\"cerrejon2\">\n  <iframe loading=\"lazy\" width=\"560\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/R1L0lrTTsFM?si=anpqci2v-jcb0590\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div>\n\n\n\n<p>La serie \u00abCerrej\u00f3n\u00bb no solo capt\u00f3 la atenci\u00f3n de millones de espectadores por las noches, sino que tambi\u00e9n desencaden\u00f3 una cobertura medi\u00e1tica nacional sin precedentes, con once peri\u00f3dicos publicando las denuncias al d\u00eda siguiente.<\/p>\n\n\n\n<p><strong>PARTE 3:<\/strong><\/p>\n\n\n\n<div id=\"cerrejon3\">\n <iframe loading=\"lazy\" width=\"560\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/bO_SEfc5wwM?si=4wU083vP6TnWnyG0\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div>\n\n\n\n<p>\u00abCerrej\u00f3n\u00bb se convirti\u00f3 en un hito del periodismo de investigaci\u00f3n en Colombia, demostrando el poder de los medios para sacar a la luz acuerdos cuestionables y pr\u00e1cticas controvertidas en sectores clave para la econom\u00eda y el medio ambiente del pa\u00eds. Este episodio, junto con otros trabajos de Castro Caycedo, subrayan la relevancia del periodismo comprometido con la verdad y la justicia social, marcando a \u00abCerrej\u00f3n\u00bb como una pieza hist\u00f3rica invaluable en el legado del periodismo colombiano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Septiembre y octubre de 1982. El 27 de septiembre, en el horario nocturno de la televisi\u00f3n colombiana, &#8216;Enviado Especial&#8217; present\u00f3 uno de sus episodios m\u00e1s emblem\u00e1ticos y reveladores: \u00abCerrej\u00f3n\u00bb. Bajo la direcci\u00f3n de Germ\u00e1n Castro Caycedo, quien por primera vez apareci\u00f3 con corbata azul ante las c\u00e1maras, el programa prometi\u00f3 y entreg\u00f3 una hora llena [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5448,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[145],"tags":[],"class_list":["post-4916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-qr"],"_links":{"self":[{"href":"https:\/\/germancastrocaycedo.co\/portal\/wp-json\/wp\/v2\/posts\/4916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/germancastrocaycedo.co\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/germancastrocaycedo.co\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/germancastrocaycedo.co\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/germancastrocaycedo.co\/portal\/wp-json\/wp\/v2\/comments?post=4916"}],"version-history":[{"count":6,"href":"https:\/\/germancastrocaycedo.co\/portal\/wp-json\/wp\/v2\/posts\/4916\/revisions"}],"predecessor-version":[{"id":5447,"href":"https:\/\/germancastrocaycedo.co\/portal\/wp-json\/wp\/v2\/posts\/4916\/revisions\/5447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/germancastrocaycedo.co\/portal\/wp-json\/wp\/v2\/media\/5448"}],"wp:attachment":[{"href":"https:\/\/germancastrocaycedo.co\/portal\/wp-json\/wp\/v2\/media?parent=4916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/germancastrocaycedo.co\/portal\/wp-json\/wp\/v2\/categories?post=4916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/germancastrocaycedo.co\/portal\/wp-json\/wp\/v2\/tags?post=4916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}